{"id":2360,"date":"2019-07-20T17:39:45","date_gmt":"2019-07-20T15:39:45","guid":{"rendered":"https:\/\/jp2doc.pl\/it\/?p=2360"},"modified":"2019-07-20T17:39:45","modified_gmt":"2019-07-20T15:39:45","slug":"accoglienza-fra-servizio-e-ascolto","status":"publish","type":"post","link":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/","title":{"rendered":"Accoglienza: fra servizio e ascolto"},"content":{"rendered":"<p>Rif.: <em>Gn 18,1-10; Sal 14\/15,2-5; Col 1,24-28; Lc 10,38-42<\/em><\/p>\n<p>L\u2019ospitalit\u00e0 \u00e8 uno dei cardini della Sacra Scrittura tanto da intravvedere nell\u2019accoglienza dell\u2019uomo l\u2019accoglienza di Dio stesso. Le letture di questa domenica sono uno splendido trittico che, attraverso le scene di Abramo, di Marta e di Paolo, sviluppano il tema dell\u2019ospitalit\u00e0. Al contrario di quanto si pensa essa non si limita ad caloroso benvenuto o all\u2019offerta di cibo e ristoro, l\u2019accoglienza \u00e8 qui presentata come un cammino spirituale che dall\u2019uomo conduce a Dio, anzi nell\u2019uomo ci fa vedere Dio che viene a noi pellegrino nel mondo.<\/p>\n<p>Da un lato di questo trittico ideale vediamo Abramo che, vecchio, stanco e forse ancora sofferente per la recente circoncisione, si precipita incontro ai tre che scorge da lontano invitandoli a fermarsi presso di lui. Abramo corre, si prostra, va, sceglie il vitello, lo d\u00e0 al servo, porta cibo e bevande agli ospiti e poi rimane \u201cin piedi\u201d presso di loro per prevenirne desideri e bisogni e servirli adeguatamente. In questo modo egli d\u00e0 prova di un\u2019accoglienza degna di questo nome e ha nei riguardi degli ospiti un atteggiamento di servizio generoso al quale sacrifica il proprio disagio e la propria sofferenza. Alla fine del pranzo, Dio (perch\u00e9 di Dio si tratta) mostrer\u00e0 di aver gradito la disponibilit\u00e0 di Abramo e gli garantisce la nascita del figlio lungamente e finora inutilmente desiderato.<\/p>\n<p>Dall\u2019altro lato c\u2019\u00e8 la scena evangelica: a Marta, che si lamenta con il Signore perch\u00e9 la sorella Maria l\u2019ha lasciata sola a servire per ascoltarlo, Ges\u00f9 risponde: \u201cMarta, Marta, tu ti affanni e ti agiti per molte cose, ma di una cosa sola c\u2019\u00e8 bisogno\u201d.<\/p>\n<p>Marta era forse emozionata, certamente indaffarata per dare degna ospitalit\u00e0 al Maestro, ma Dio non vuole per s\u00e9 un buon pranzo o una fresca bevanda. Egli venuto per dare, anzi per darsi e ci\u00f2 che cerca \u00e8 la nostra disponibilit\u00e0 interiore, l\u2019ascolto incondizionato, \u201cinnamorato\u201d della sua Parola e la nostra vicinanza. Maria invece era seduta ai piedi di Ges\u00f9, apparentemente senza fare nulla, ma quella parola modellava la sua anima, la rendeva \u201camica\u201d di Cristo, ella era pronta ad agire secondo quanto apprendeva da Lui. In entrambe le scene Abramo e Maria hanno stabilito un rapporto \u201cintimo, confidenziale\u201d e tutte e due ricevono un dono: il primo un figlio e la seconda la \u201cparte migliore che non le sar\u00e0 tolta\u201d (la Parola).<\/p>\n<p>Simbolicamente nella prima scena abbiamo visto che Abramo ha messo a servizio di Dio il proprio agire (ha accolto Dio mettendosi a servizio dell\u2019uomo), mentre Maria \u00e8 stata rapita dall\u2019ascolto (essa accoglie Dio nell\u2019ascolto della sua parola, nella contemplazione del suo significato) rimane ora la terza parte: in essa vediamo che Paolo, stretto dalle sofferenze e dalle difficolt\u00e0, scrive ai Colossesi \u201cSono lieto delle sofferenze che sopporto per voi e do compimento a ci\u00f2 che, dei patimenti di Cristo, manca nella mia carne\u201d. Siamo finalmente arrivati al punto pi\u00f9 alto di questo cammino spirituale che \u00e8 l\u2019accoglienza: esso inizia con l\u2019accogliere l\u2019uomo per arrivare ad accogliere Cristo, non pi\u00f9 come ospite, ma come colui che ci \u00e8 pi\u00f9 caro di noi stessi, come colui al quale uniformarci non solo con la volont\u00e0 ed il cuore, ma ancor di pi\u00f9 con la sofferenza, per essergli simili, per completare in noi la sua immagine cara ed amata di Crocifisso prima e di Risorto poi. E nella sofferenza offrirsi a Dio per il bene degli altri, senza pi\u00f9 desideri o rivalse, offrirsi perch\u00e9 Cristo si \u00e8 offerto, soffrire per amore perch\u00e9 Egli per amore ha sofferto. Un cammino arduo si apre dinanzi alla nostra fede, una cammino eroico cui non tutti sono chiamati, ma a ciascuno di noi viene prima o poi offerta la possibilit\u00e0 di accogliere un uomo ed in lui accogliere Dio.<\/p>\n<p><strong>L.R.<\/strong><\/p>\n<p><em>Fot. Kelsey Chance\/Unsplash.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XVI Domenica del Tempo Ordinario<\/p>\n","protected":false},"author":5,"featured_media":2361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4,13,14],"tags":[82,104,272,273],"class_list":["post-2360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-strona-glowna-najnowsze","category-strona-glowna-slider","tag-lisetta_romano","tag-maria","tag-marta","tag-ospitalita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accoglienza: fra servizio e ascolto - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accoglienza: fra servizio e ascolto - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\" \/>\n<meta property=\"og:description\" content=\"XVI Domenica del Tempo Ordinario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-20T15:39:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1613\" \/>\n\t<meta property=\"og:image:height\" content=\"1075\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"juliasercanka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"juliasercanka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\"},\"author\":{\"name\":\"juliasercanka\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe\"},\"headline\":\"Accoglienza: fra servizio e ascolto\",\"datePublished\":\"2019-07-20T15:39:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\"},\"wordCount\":649,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg\",\"keywords\":[\"Lisetta_Romano\",\"Maria\",\"Marta\",\"ospitalita\"],\"articleSection\":[\"Blog\",\"Strona g\u0142\u00f3wna - najnowsze\",\"Strona g\u0142\u00f3wna - slider\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\",\"url\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\",\"name\":\"Accoglienza: fra servizio e ascolto - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"isPartOf\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg\",\"datePublished\":\"2019-07-20T15:39:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage\",\"url\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg\",\"contentUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg\",\"width\":1613,\"height\":1075},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jp2doc.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accoglienza: fra servizio e ascolto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#website\",\"url\":\"https:\/\/jp2doc.pl\/it\/\",\"name\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jp2doc.pl\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\",\"name\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"url\":\"https:\/\/jp2doc.pl\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png\",\"width\":115,\"height\":115,\"caption\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe\",\"name\":\"juliasercanka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g\",\"caption\":\"juliasercanka\"},\"url\":\"https:\/\/jp2doc.pl\/it\/author\/juliasercanka\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accoglienza: fra servizio e ascolto - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/","og_locale":"it_IT","og_type":"article","og_title":"Accoglienza: fra servizio e ascolto - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","og_description":"XVI Domenica del Tempo Ordinario","og_url":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/","og_site_name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","article_published_time":"2019-07-20T15:39:45+00:00","og_image":[{"width":1613,"height":1075,"url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg","type":"image\/jpeg"}],"author":"juliasercanka","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"juliasercanka","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#article","isPartOf":{"@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/"},"author":{"name":"juliasercanka","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe"},"headline":"Accoglienza: fra servizio e ascolto","datePublished":"2019-07-20T15:39:45+00:00","mainEntityOfPage":{"@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/"},"wordCount":649,"commentCount":0,"publisher":{"@id":"https:\/\/jp2doc.pl\/it\/#organization"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage"},"thumbnailUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg","keywords":["Lisetta_Romano","Maria","Marta","ospitalita"],"articleSection":["Blog","Strona g\u0142\u00f3wna - najnowsze","Strona g\u0142\u00f3wna - slider"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/","url":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/","name":"Accoglienza: fra servizio e ascolto - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","isPartOf":{"@id":"https:\/\/jp2doc.pl\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage"},"thumbnailUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg","datePublished":"2019-07-20T15:39:45+00:00","breadcrumb":{"@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#primaryimage","url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg","contentUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2019\/07\/kelsey-chance-ZrhtQyGFG6s-unsplash.jpg","width":1613,"height":1075},{"@type":"BreadcrumbList","@id":"https:\/\/jp2doc.pl\/it\/2019\/07\/20\/accoglienza-fra-servizio-e-ascolto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jp2doc.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Accoglienza: fra servizio e ascolto"}]},{"@type":"WebSite","@id":"https:\/\/jp2doc.pl\/it\/#website","url":"https:\/\/jp2doc.pl\/it\/","name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","description":"","publisher":{"@id":"https:\/\/jp2doc.pl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jp2doc.pl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/jp2doc.pl\/it\/#organization","name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","url":"https:\/\/jp2doc.pl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png","contentUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png","width":115,"height":115,"caption":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe","name":"juliasercanka","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g","caption":"juliasercanka"},"url":"https:\/\/jp2doc.pl\/it\/author\/juliasercanka\/"}]}},"_links":{"self":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts\/2360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/comments?post=2360"}],"version-history":[{"count":2,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts\/2360\/revisions"}],"predecessor-version":[{"id":2363,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts\/2360\/revisions\/2363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/media\/2361"}],"wp:attachment":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/media?parent=2360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/categories?post=2360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/tags?post=2360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}