{"id":3154,"date":"2024-04-27T14:36:26","date_gmt":"2024-04-27T12:36:26","guid":{"rendered":"https:\/\/jp2doc.pl\/it\/?p=3154"},"modified":"2024-04-27T14:36:27","modified_gmt":"2024-04-27T12:36:27","slug":"il-buon-pastore-da-la-propria-vita-per-le-pecore","status":"publish","type":"post","link":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/","title":{"rendered":"Il buon pastore d\u00e0 la propria vita per le pecore"},"content":{"rendered":"\n<p>Nella domenica del buon pastore, ascoltiamo nuovamente che Ges\u00f9 \u00e8 il buon pastore, \u00abil buon pastore d\u00e0 la propria vita per le pecore. Il mercenario \u2013 che non \u00e8 pastore e al quale le pecore non appartengono \u2013 vede venire il lupo, abbandona le pecore e fugge, e il lupo le rapisce e le disperde; perch\u00e9 \u00e8 un mercenario e non gli importa delle pecore\u00bb. La relazione tra il pastore e le sue pecore \u00e8 come quella di un padre con i figli; ossia il padre non lascia mai i suoi figli e sempre li protegge intorno. Il rapporto tra Ges\u00f9 e i discepoli \u00e8 come il pastore e le pecore, anche come padre e figli, quello che \u00e8 alla base dell\u2019amore e cura incondizionata. Questo messaggio ci conferma che nessuno \u00e8 solo, perch\u00e9 Ges\u00f9 sempre sta accanto e non ci abbandona. Ogni tanto, per salvare la vita delle pecore, il buon pastore anche pu\u00f2 dare la propria vita. Ges\u00f9 per la nostra salvezza ha gi\u00e0 dato la sua vita. Quest\u2019amore \u00e8 una fonte di nutrimento spirituale per ogni circostanza della vita. Ovvero, una testimonianza di speranza per vivere in qualsiasi situazione.<\/p>\n\n\n\n<p>Questa settimana sono stata a Breslavia, in Polonia, e ho potuto anche visitare la casa di Edith Stein. Edith Stein, con la sua sincera ricerca per la verit\u00e0, prima si \u00e8 dedicata come filosofa, poi dopo la lettura di San Teresa d\u2019Avila, ha sacrificato la sua vita come monaca carmelitana. Il suo supremo sacrificio \u00e8 il martirio come cattolica con radici ebraiche, che porta un esempio eccezionale come il buon pastore. La sua vita \u00e8 breve ma intensa: quando era ancora piccola, cercava di aiutare la famiglia; come adolescente era diligente per lo studio; da adulta, stava gridando per i diritti delle donne e la popolazione ebraica; infine, come monaca carmelitana, contemplando e pregando per la Santa Chiesa e il mondo intero, fino a rinunciare alla propria vita per questo. In sintesi, attraverso la sua vita e il suo lavoro, Edith Stein ha incarnato il concetto del \u201cbuon pastore\u201d che d\u00e0 la vita per le sue pecore, offrendo un esempio tangibile per tutti noi \u2013 coloro che hanno fatto la scelta di seguire Ges\u00f9 Cristo e dedicare la vita propria per essere pi\u00f9 evidenti come <em>Imago Dei<\/em>.<\/p>\n\n\n\n<p>Il comandamento che Ges\u00f9 ha lasciato \u00e8 amarsi gli uni gli altri, come Lui ci ha amati. \u00abNessuno ha un amore pi\u00f9 grande di questo: dare la vita per i propri amici\u00bb (Gv 15, 13). Pertanto, Ges\u00f9 cercava di riempire la volont\u00e0 del Padre, come anche Edith Stein cercava di compiere la volont\u00e0 di Ges\u00f9. Come diceva San Giovanni Paolo II,<\/p>\n\n\n\n<p><em>\u00abL\u2019allegoria del Buon Pastore e, in essa, l\u2019immagine dell\u2019ovile hanno fondamentale importanza per capire che cosa \u00e8 la Chiesa e quali compiti essa ha da adempiere nella storia dell\u2019uomo. La Chiesa non solo deve essere \u201covile\u201d, ma deve realizzare questo mistero, che sempre si sta compiendo tra Cristo e l\u2019uomo: il mistero del Buon Pastore, che offre la sua vita per le pecore\u00bb<\/em><a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a>.<\/p>\n\n\n\n<p><strong>Sophia Lilin Wu<\/strong>, dottorando di Pontificia Universit\u00e0 Gregoriana.<\/p>\n\n\n\n<p><em>Fot. Jasmin Schreiber\/Unsplash.com<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Giovanni Paolo II, \u00abUdienza Generale\u00bb, 9 maggio 1979, <a href=\"https:\/\/www.vatican.va\/content\/john-paul-ii\/it\/audiences\/1979\/documents\/hf_jp-ii_aud_19790509.html\">https:\/\/www.vatican.va\/content\/john-paul-ii\/it\/audiences\/1979\/documents\/hf_jp-ii_aud_19790509.html<\/a> (accesso: 21.04.2024).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IV Domenica di Pasqua<\/p>\n","protected":false},"author":5,"featured_media":2611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4,13,14],"tags":[],"class_list":["post-3154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-strona-glowna-najnowsze","category-strona-glowna-slider"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il buon pastore d\u00e0 la propria vita per le pecore - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il buon pastore d\u00e0 la propria vita per le pecore - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\" \/>\n<meta property=\"og:description\" content=\"IV Domenica di Pasqua\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T12:36:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-27T12:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"juliasercanka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"juliasercanka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\"},\"author\":{\"name\":\"juliasercanka\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe\"},\"headline\":\"Il buon pastore d\u00e0 la propria vita per le pecore\",\"datePublished\":\"2024-04-27T12:36:26+00:00\",\"dateModified\":\"2024-04-27T12:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\"},\"wordCount\":536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg\",\"articleSection\":[\"Blog\",\"Strona g\u0142\u00f3wna - najnowsze\",\"Strona g\u0142\u00f3wna - slider\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\",\"url\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\",\"name\":\"Il buon pastore d\u00e0 la propria vita per le pecore - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"isPartOf\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg\",\"datePublished\":\"2024-04-27T12:36:26+00:00\",\"dateModified\":\"2024-04-27T12:36:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage\",\"url\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg\",\"contentUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jp2doc.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il buon pastore d\u00e0 la propria vita per le pecore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#website\",\"url\":\"https:\/\/jp2doc.pl\/it\/\",\"name\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jp2doc.pl\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\",\"name\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"url\":\"https:\/\/jp2doc.pl\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png\",\"width\":115,\"height\":115,\"caption\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe\",\"name\":\"juliasercanka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g\",\"caption\":\"juliasercanka\"},\"url\":\"https:\/\/jp2doc.pl\/it\/author\/juliasercanka\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il buon pastore d\u00e0 la propria vita per le pecore - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/","og_locale":"it_IT","og_type":"article","og_title":"Il buon pastore d\u00e0 la propria vita per le pecore - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","og_description":"IV Domenica di Pasqua","og_url":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/","og_site_name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","article_published_time":"2024-04-27T12:36:26+00:00","article_modified_time":"2024-04-27T12:36:27+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg","type":"image\/jpeg"}],"author":"juliasercanka","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"juliasercanka","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#article","isPartOf":{"@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/"},"author":{"name":"juliasercanka","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe"},"headline":"Il buon pastore d\u00e0 la propria vita per le pecore","datePublished":"2024-04-27T12:36:26+00:00","dateModified":"2024-04-27T12:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/"},"wordCount":536,"commentCount":0,"publisher":{"@id":"https:\/\/jp2doc.pl\/it\/#organization"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage"},"thumbnailUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg","articleSection":["Blog","Strona g\u0142\u00f3wna - najnowsze","Strona g\u0142\u00f3wna - slider"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/","url":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/","name":"Il buon pastore d\u00e0 la propria vita per le pecore - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","isPartOf":{"@id":"https:\/\/jp2doc.pl\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage"},"thumbnailUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg","datePublished":"2024-04-27T12:36:26+00:00","dateModified":"2024-04-27T12:36:27+00:00","breadcrumb":{"@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#primaryimage","url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg","contentUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2021\/04\/jasmin-schreiber-A15ooIKNhHg-unsplash.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/jp2doc.pl\/it\/2024\/04\/27\/il-buon-pastore-da-la-propria-vita-per-le-pecore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jp2doc.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Il buon pastore d\u00e0 la propria vita per le pecore"}]},{"@type":"WebSite","@id":"https:\/\/jp2doc.pl\/it\/#website","url":"https:\/\/jp2doc.pl\/it\/","name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","description":"","publisher":{"@id":"https:\/\/jp2doc.pl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jp2doc.pl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/jp2doc.pl\/it\/#organization","name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","url":"https:\/\/jp2doc.pl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png","contentUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png","width":115,"height":115,"caption":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/6110109e80abb51f6fac4824777eabfe","name":"juliasercanka","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/266a66e864556e22d55d61b6b10c97fab9060767b738564bcd109f3997e372bc?s=96&d=mm&r=g","caption":"juliasercanka"},"url":"https:\/\/jp2doc.pl\/it\/author\/juliasercanka\/"}]}},"_links":{"self":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts\/3154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/comments?post=3154"}],"version-history":[{"count":1,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts\/3154\/revisions"}],"predecessor-version":[{"id":3155,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts\/3154\/revisions\/3155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/media\/2611"}],"wp:attachment":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/media?parent=3154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/categories?post=3154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/tags?post=3154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}