{"id":22,"count":6,"description":"","link":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/","name":"giovanni paolo II","slug":"giovanni-paolo-ii","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>giovanni paolo II Archives - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"giovanni paolo II Archives - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/\",\"url\":\"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/\",\"name\":\"giovanni paolo II Archives - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"isPartOf\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jp2doc.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"giovanni paolo II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#website\",\"url\":\"https:\/\/jp2doc.pl\/it\/\",\"name\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jp2doc.pl\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#organization\",\"name\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\",\"url\":\"https:\/\/jp2doc.pl\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png\",\"width\":115,\"height\":115,\"caption\":\"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma\"},\"image\":{\"@id\":\"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"giovanni paolo II Archives - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/","og_locale":"it_IT","og_type":"article","og_title":"giovanni paolo II Archives - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","og_url":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/","og_site_name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/","url":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/","name":"giovanni paolo II Archives - Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","isPartOf":{"@id":"https:\/\/jp2doc.pl\/it\/#website"},"breadcrumb":{"@id":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/jp2doc.pl\/it\/tag\/giovanni-paolo-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jp2doc.pl\/it\/"},{"@type":"ListItem","position":2,"name":"giovanni paolo II"}]},{"@type":"WebSite","@id":"https:\/\/jp2doc.pl\/it\/#website","url":"https:\/\/jp2doc.pl\/it\/","name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","description":"","publisher":{"@id":"https:\/\/jp2doc.pl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jp2doc.pl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/jp2doc.pl\/it\/#organization","name":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma","url":"https:\/\/jp2doc.pl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png","contentUrl":"https:\/\/jp2doc.pl\/it\/wp-content\/uploads\/sites\/3\/2017\/03\/cropped-logo.png","width":115,"height":115,"caption":"Centro di Documentazione e Studio del Pontificato di Giovanni Paolo II a Roma"},"image":{"@id":"https:\/\/jp2doc.pl\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/tags\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jp2doc.pl\/it\/wp-json\/wp\/v2\/posts?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}